{"id":7873,"date":"2024-04-01T14:15:15","date_gmt":"2024-04-01T21:15:15","guid":{"rendered":"https:\/\/alcierrenoticias.com\/?p=7873"},"modified":"2024-04-01T14:15:32","modified_gmt":"2024-04-01T21:15:32","slug":"reprogramacion-del-horario-de-inauguracion-de-la-pista-de-hielo-sera-a-las-8-de-la-noche","status":"publish","type":"post","link":"https:\/\/alcierrenoticias.com\/index.php\/2024\/04\/01\/reprogramacion-del-horario-de-inauguracion-de-la-pista-de-hielo-sera-a-las-8-de-la-noche\/","title":{"rendered":"Reprogramaci\u00f3n del horario de inauguraci\u00f3n de la pista de hielo; ser\u00e1 a las 8 de la noche."},"content":{"rendered":"<p>El horario de inauguraci\u00f3n de la Pista de Hielo, una de las atracciones principales del Festival de la Fundaci\u00f3n de Delicias en su 91 aniversario, se re program\u00f3 para las 8 de la noche de este lunes primero de abril. Esta modificaci\u00f3n se debe a motivos log\u00edsticos, seg\u00fan inform\u00f3 Daniela Rodarte, titular de Eventos del Gobierno Municipal y responsable de la organizaci\u00f3n del Festival.<\/p>\n<p>A partir del martes, la pista de hielo estar\u00e1 abierta durante todo el mes de abril en los siguientes horarios: de 9 de la ma\u00f1ana a 1 de la tarde y de 4 de la tarde a 10 de la noche, brindando as\u00ed una oportunidad para que los ciudadanos disfruten de esta emocionante atracci\u00f3n.<\/p>\n<p>Por \u00faltimo, Daniela Rodarte solicit\u00f3 la comprensi\u00f3n de la ciudadan\u00eda ante este cambio en el horario, agreg\u00f3, que ya durante todo lo que resta del mes las familias delicienses podr\u00e1n disfrutar plenamente de esta atracci\u00f3n.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El horario de inauguraci\u00f3n de la Pista de Hielo, una de las atracciones principales del Festival de la Fundaci\u00f3n de Delicias en su 91 aniversario, se re program\u00f3 para las 8 de la noche de este lunes primero de abril. Esta modificaci\u00f3n se debe a motivos log\u00edsticos, seg\u00fan inform\u00f3 Daniela Rodarte, titular de Eventos del Gobierno Municipal y responsable de la organizaci\u00f3n del Festival. A partir del martes, la pista de hielo estar\u00e1 abierta durante todo el mes de abril en los siguientes horarios: de 9 de la ma\u00f1ana a 1 de la tarde y de 4 de la tarde a 10 de la noche, brindando as\u00ed una oportunidad para que los ciudadanos disfruten de esta emocionante atracci\u00f3n. Por \u00faltimo, Daniela Rodarte solicit\u00f3 la comprensi\u00f3n de la ciudadan\u00eda ante este cambio en el horario, agreg\u00f3, que ya durante todo lo que resta del mes las familias delicienses podr\u00e1n disfrutar plenamente de esta atracci\u00f3n.<\/p>\n","protected":false},"author":2,"featured_media":7874,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"advanced_seo_description":"","jetpack_seo_html_title":"","jetpack_seo_noindex":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false},"version":2}},"categories":[135,7,11],"tags":[],"class_list":["post-7873","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-lo-mas-leido","category-local","category-principal"],"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/i0.wp.com\/alcierrenoticias.com\/wp-content\/uploads\/2024\/04\/WhatsApp-Image-2024-03-31-at-4.26.14-PM-e1712006054108.jpeg?fit=400%2C400&ssl=1","amp_enabled":true,"_links":{"self":[{"href":"https:\/\/alcierrenoticias.com\/index.php\/wp-json\/wp\/v2\/posts\/7873","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/alcierrenoticias.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/alcierrenoticias.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/alcierrenoticias.com\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/alcierrenoticias.com\/index.php\/wp-json\/wp\/v2\/comments?post=7873"}],"version-history":[{"count":1,"href":"https:\/\/alcierrenoticias.com\/index.php\/wp-json\/wp\/v2\/posts\/7873\/revisions"}],"predecessor-version":[{"id":7875,"href":"https:\/\/alcierrenoticias.com\/index.php\/wp-json\/wp\/v2\/posts\/7873\/revisions\/7875"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/alcierrenoticias.com\/index.php\/wp-json\/wp\/v2\/media\/7874"}],"wp:attachment":[{"href":"https:\/\/alcierrenoticias.com\/index.php\/wp-json\/wp\/v2\/media?parent=7873"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/alcierrenoticias.com\/index.php\/wp-json\/wp\/v2\/categories?post=7873"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/alcierrenoticias.com\/index.php\/wp-json\/wp\/v2\/tags?post=7873"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}