{"id":3083,"date":"2023-06-16T19:53:09","date_gmt":"2023-06-17T01:53:09","guid":{"rendered":"https:\/\/alcierrenoticias.com\/?p=3083"},"modified":"2023-06-16T19:53:09","modified_gmt":"2023-06-17T01:53:09","slug":"inauguran-torneo-estatal-de-softbol-magisterial-de-la-seccion-8","status":"publish","type":"post","link":"https:\/\/alcierrenoticias.com\/index.php\/2023\/06\/16\/inauguran-torneo-estatal-de-softbol-magisterial-de-la-seccion-8\/","title":{"rendered":"Inauguran Torneo Estatal de Softbol Magisterial de la Secci\u00f3n 8."},"content":{"rendered":"<p>Este viernes el Presidente Municipal, Jes\u00fas Valenciano, asisti\u00f3 a la inauguraci\u00f3n del Torneo Estatal de Softbol Magisterial de la secci\u00f3n 8, en donde refrend\u00f3 su compromiso con el deporte y la educaci\u00f3n, con el sindicato y con lo que los profesores que \u201crepresentan, sue\u00f1os y esperanzas\u201d, resalt\u00f3.<\/p>\n<p>Destac\u00f3 que desde Presidencia Municipal se han apoyado a m\u00e1s de 100 escuelas y se han entregado 7 mil becas, para fomentar la educaci\u00f3n, y finalmente invit\u00f3 a todos los presentes al juego de b\u00e9isbol de Algodoneros Vs Mazorqueros, en el Gran Estadio de Delicias.<\/p>\n<p>Por su parte el profesor Eduardo Zendejas Amparan, coordinador estatal de la secci\u00f3n 8, se dijo contento de recuperar despu\u00e9s de 4 a\u00f1os una convivencia deportiva como esta, \u201clo que significa que hay salud\u201d mencion\u00f3, les dio la bienvenida a todos los estudiantes y familias presentes, agradeci\u00f3 el apoyo de las autoridades educativas y del Alcalde Jes\u00fas Valenciano.<\/p>\n<p>Resalt\u00f3 que son tres categor\u00edas en las que se competir\u00e1n, incluyendo la femenil, y que ser\u00e1n m\u00e1s de 400 jugadores, distribuidos en 28 equipos, y despu\u00e9s de su discurso inaugur\u00f3 oficialmente el Torneo de Softbol Estatal Magisterial y dese\u00f3 que gane el mejor.<\/p>\n<p>Asimismo, Miguel Espinoza, coordinador Regi\u00f3n Delicias SNTE, dirigi\u00f3 unas palabras de bienvenida a los jugadores de Delicias, Ju\u00e1rez, Guachochi, Cuauht\u00e9moc, Camargo, Saucillo, Chihuahua y Jim\u00e9nez, y anticip\u00f3 estar\u00e1n atentos durante estos d\u00edas para garantizar un evento exitoso; cabe destacar que se cont\u00f3 con la presencia de H\u00e9ctor V\u00e1zquez, coordinador regional secci\u00f3n 8 Meoqui y dem\u00e1s autoridades del SNTE secci\u00f3n 8 de la regi\u00f3n.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Este viernes el Presidente Municipal, Jes\u00fas Valenciano, asisti\u00f3 a la inauguraci\u00f3n del Torneo Estatal de Softbol Magisterial de la secci\u00f3n 8, en donde refrend\u00f3 su compromiso con el deporte y la educaci\u00f3n, con el sindicato y con lo que los profesores que \u201crepresentan, sue\u00f1os y esperanzas\u201d, resalt\u00f3. Destac\u00f3 que desde Presidencia Municipal se han apoyado a m\u00e1s de 100 escuelas y se han entregado 7 mil becas, para fomentar la educaci\u00f3n, y finalmente invit\u00f3 a todos los presentes al juego de b\u00e9isbol de Algodoneros Vs Mazorqueros, en el Gran Estadio de Delicias. Por su parte el profesor Eduardo Zendejas Amparan, coordinador estatal de la secci\u00f3n 8, se dijo contento de recuperar despu\u00e9s de 4 a\u00f1os una convivencia deportiva como esta, \u201clo que significa que hay salud\u201d mencion\u00f3, les dio la bienvenida a todos los estudiantes y familias presentes, agradeci\u00f3 el apoyo de las autoridades educativas y del Alcalde Jes\u00fas Valenciano. Resalt\u00f3 que son tres categor\u00edas en las que se competir\u00e1n, incluyendo la femenil, y que ser\u00e1n m\u00e1s de 400 jugadores, distribuidos en 28 equipos, y despu\u00e9s de su discurso inaugur\u00f3 oficialmente el Torneo de Softbol Estatal Magisterial y dese\u00f3 que gane el mejor. Asimismo, Miguel Espinoza, coordinador Regi\u00f3n Delicias SNTE, dirigi\u00f3 unas palabras de bienvenida a los jugadores de Delicias, Ju\u00e1rez, Guachochi, Cuauht\u00e9moc, Camargo, Saucillo, Chihuahua y Jim\u00e9nez, y anticip\u00f3 estar\u00e1n atentos durante estos d\u00edas para garantizar un evento exitoso; cabe destacar que se cont\u00f3 con la presencia de H\u00e9ctor V\u00e1zquez, coordinador regional secci\u00f3n 8 Meoqui y dem\u00e1s autoridades del SNTE secci\u00f3n 8 de la regi\u00f3n.<\/p>\n","protected":false},"author":2,"featured_media":3084,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"advanced_seo_description":"","jetpack_seo_html_title":"","jetpack_seo_noindex":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false},"version":2}},"categories":[135,7,11],"tags":[],"class_list":["post-3083","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-lo-mas-leido","category-local","category-principal"],"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/i0.wp.com\/alcierrenoticias.com\/wp-content\/uploads\/2023\/06\/WhatsApp-Image-2023-06-16-at-11.41.16-AM.jpeg?fit=1280%2C758&ssl=1","amp_enabled":true,"_links":{"self":[{"href":"https:\/\/alcierrenoticias.com\/index.php\/wp-json\/wp\/v2\/posts\/3083","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/alcierrenoticias.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/alcierrenoticias.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/alcierrenoticias.com\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/alcierrenoticias.com\/index.php\/wp-json\/wp\/v2\/comments?post=3083"}],"version-history":[{"count":1,"href":"https:\/\/alcierrenoticias.com\/index.php\/wp-json\/wp\/v2\/posts\/3083\/revisions"}],"predecessor-version":[{"id":3085,"href":"https:\/\/alcierrenoticias.com\/index.php\/wp-json\/wp\/v2\/posts\/3083\/revisions\/3085"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/alcierrenoticias.com\/index.php\/wp-json\/wp\/v2\/media\/3084"}],"wp:attachment":[{"href":"https:\/\/alcierrenoticias.com\/index.php\/wp-json\/wp\/v2\/media?parent=3083"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/alcierrenoticias.com\/index.php\/wp-json\/wp\/v2\/categories?post=3083"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/alcierrenoticias.com\/index.php\/wp-json\/wp\/v2\/tags?post=3083"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}