{"id":3048,"date":"2023-06-14T15:25:22","date_gmt":"2023-06-14T21:25:22","guid":{"rendered":"https:\/\/alcierrenoticias.com\/?p=3048"},"modified":"2023-06-14T15:25:22","modified_gmt":"2023-06-14T21:25:22","slug":"capacitan-a-funcionarios-de-meoqui-sobre-uso-responsable-de-la-linea-de-emergencias-911","status":"publish","type":"post","link":"https:\/\/alcierrenoticias.com\/index.php\/2023\/06\/14\/capacitan-a-funcionarios-de-meoqui-sobre-uso-responsable-de-la-linea-de-emergencias-911\/","title":{"rendered":"Capacitan a funcionarios de Meoqui sobre uso responsable de la l\u00ednea de emergencias 911."},"content":{"rendered":"<p>El 85% de los llamados son improcedentes, se busca crear conciencia en la ciudadan\u00eda<\/p>\n<p>El equipo de Gobierno de Meoqui de la administraci\u00f3n 2021-2024, encabezado por la alcaldesa Miriam Soto, recibi\u00f3 una capacitaci\u00f3n por parte de la Direcci\u00f3n de Seguridad P\u00fablica, a trav\u00e9s de la coordinaci\u00f3n de la l\u00ednea de emergencias, con el tema del uso responsable del n\u00famero 911, esto, debido a que hay un alto \u00edndice de llamados improcedentes, alcanzando un promedio del 85%, siendo una de las dudas recurrentes por parte de la ciudadan\u00eda al momento de realizar sus reportes al momento de encontrarse en una situaci\u00f3n que ponga en riesgo la integridad de sus familias o bienes.<\/p>\n<p>El Gobierno de la arquitecta Miriam Soto se ha caracterizado por tener una cercan\u00eda especial con la ciudadan\u00eda, implementando programas como \u201cMi\u00e9rcoles con tu Alcaldesa\u201d, \u201cPrograma 24 Horas\u201d y \u201cPor Amor a Meoqui\u201d donde la alcaldesa y los funcionarios atienden de manera directa y sin previa cita a las familias meoquenses, es por eso que el objetivo es que su equipo de colaboradores comprendan el correcto funcionamiento de las diferentes dependencias para as\u00ed dar una mejor atenci\u00f3n y orientaci\u00f3n ante cuestionamientos del por qu\u00e9 se piden tantos datos o que en ocasiones tarda en entrar los llamados al 911.<\/p>\n<p>Dentro de la capacitaci\u00f3n, Sarah\u00ed Reyes Mercado, Coordinadora de la l\u00ednea de Emergencias realiz\u00f3 una amplia explicaci\u00f3n a los funcionarios sobre el protocolo de atenci\u00f3n a los llamados, compartiendo que lo primero que se pregunta es: \u00bfCu\u00e1l es la emergencia?, \u00bfD\u00f3nde es el lugar en que se encuentra? Y datos como nombre del usuario, direcci\u00f3n y n\u00famero de contacto.<\/p>\n<p>\u201cLa l\u00ednea de emergencia 911 es un punto muy importante de lo que es la Seguridad P\u00fablica dentro del municipio de Meoqui, el C4 en Meoqui es un grupo gestor que canaliza las llamadas a las instancias que el usuario requiere como lo es Cruz Roja, Bomberos, Protecci\u00f3n Civil o Guardia Nacional seg\u00fan sea el caso\u201d mencion\u00f3 la coordinadora.<\/p>\n<p>Por \u00faltimo, la coordinadora de la L\u00ednea de Emergencias, comparti\u00f3 ante los funcionarios que de 200 llamados que se reciben en promedio al d\u00eda, solamente alrededor de 30 son procedentes, significando que un 85% son llamadas de broma o en diferentes ocasiones por peque\u00f1os que al utilizar el tel\u00e9fono celular marcan al 911, generando as\u00ed que las l\u00edneas est\u00e9n ocupadas, pues toda llamada tiene que ser atendida.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El 85% de los llamados son improcedentes, se busca crear conciencia en la ciudadan\u00eda El equipo de Gobierno de Meoqui de la administraci\u00f3n 2021-2024, encabezado por la alcaldesa Miriam Soto, recibi\u00f3 una capacitaci\u00f3n por parte de la Direcci\u00f3n de Seguridad P\u00fablica, a trav\u00e9s de la coordinaci\u00f3n de la l\u00ednea de emergencias, con el tema del uso responsable del n\u00famero 911, esto, debido a que hay un alto \u00edndice de llamados improcedentes, alcanzando un promedio del 85%, siendo una de las dudas recurrentes por parte de la ciudadan\u00eda al momento de realizar sus reportes al momento de encontrarse en una situaci\u00f3n que ponga en riesgo la integridad de sus familias o bienes. El Gobierno de la arquitecta Miriam Soto se ha caracterizado por tener una cercan\u00eda especial con la ciudadan\u00eda, implementando programas como \u201cMi\u00e9rcoles con tu Alcaldesa\u201d, \u201cPrograma 24 Horas\u201d y \u201cPor Amor a Meoqui\u201d donde la alcaldesa y los funcionarios atienden de manera directa y sin previa cita a las familias meoquenses, es por eso que el objetivo es que su equipo de colaboradores comprendan el correcto funcionamiento de las diferentes dependencias para as\u00ed dar una mejor atenci\u00f3n y orientaci\u00f3n ante cuestionamientos del por qu\u00e9 se piden tantos datos o que en ocasiones tarda en entrar los llamados al 911. Dentro de la capacitaci\u00f3n, Sarah\u00ed Reyes Mercado, Coordinadora de la l\u00ednea de Emergencias realiz\u00f3 una amplia explicaci\u00f3n a los funcionarios sobre el protocolo de atenci\u00f3n a los llamados, compartiendo que lo primero que se pregunta es: \u00bfCu\u00e1l es la emergencia?, \u00bfD\u00f3nde es el lugar en que se encuentra? Y datos como nombre del usuario, direcci\u00f3n y n\u00famero de contacto. \u201cLa l\u00ednea de emergencia 911 es un punto muy importante de lo que es la Seguridad P\u00fablica dentro del municipio de Meoqui, el C4 en Meoqui es un grupo gestor que canaliza las llamadas a las instancias que el usuario requiere como lo es Cruz Roja, Bomberos, Protecci\u00f3n Civil o Guardia Nacional seg\u00fan sea el caso\u201d mencion\u00f3 la coordinadora. Por \u00faltimo, la coordinadora de la L\u00ednea de Emergencias, comparti\u00f3 ante los funcionarios que de 200 llamados que se reciben en promedio al d\u00eda, solamente alrededor de 30 son procedentes, significando que un 85% son llamadas de broma o en diferentes ocasiones por peque\u00f1os que al utilizar el tel\u00e9fono celular marcan al 911, generando as\u00ed que las l\u00edneas est\u00e9n ocupadas, pues toda llamada tiene que ser atendida.<\/p>\n","protected":false},"author":2,"featured_media":3049,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"advanced_seo_description":"","jetpack_seo_html_title":"","jetpack_seo_noindex":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false},"version":2}},"categories":[135,7,11],"tags":[],"class_list":["post-3048","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-lo-mas-leido","category-local","category-principal"],"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/i0.wp.com\/alcierrenoticias.com\/wp-content\/uploads\/2023\/06\/WhatsApp-Image-2023-06-13-at-5.28.57-PM.jpeg?fit=1600%2C900&ssl=1","amp_enabled":true,"_links":{"self":[{"href":"https:\/\/alcierrenoticias.com\/index.php\/wp-json\/wp\/v2\/posts\/3048","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/alcierrenoticias.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/alcierrenoticias.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/alcierrenoticias.com\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/alcierrenoticias.com\/index.php\/wp-json\/wp\/v2\/comments?post=3048"}],"version-history":[{"count":1,"href":"https:\/\/alcierrenoticias.com\/index.php\/wp-json\/wp\/v2\/posts\/3048\/revisions"}],"predecessor-version":[{"id":3050,"href":"https:\/\/alcierrenoticias.com\/index.php\/wp-json\/wp\/v2\/posts\/3048\/revisions\/3050"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/alcierrenoticias.com\/index.php\/wp-json\/wp\/v2\/media\/3049"}],"wp:attachment":[{"href":"https:\/\/alcierrenoticias.com\/index.php\/wp-json\/wp\/v2\/media?parent=3048"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/alcierrenoticias.com\/index.php\/wp-json\/wp\/v2\/categories?post=3048"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/alcierrenoticias.com\/index.php\/wp-json\/wp\/v2\/tags?post=3048"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}